{"id":35602,"date":"2025-01-02T13:46:12","date_gmt":"2025-01-02T11:46:12","guid":{"rendered":"https:\/\/www.believecasuals.com\/?post_type=product&#038;p=35602"},"modified":"2026-06-02T14:17:59","modified_gmt":"2026-06-02T12:17:59","slug":"open-jacket-re-w-hoody-2-pckt","status":"publish","type":"product","link":"http:\/\/www.believecasuals.com\/ar\/product\/open-jacket-re-w-hoody-2-pckt\/","title":{"rendered":"OPEN JACKET RE W HOODY 2 PCKT"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":35606,"template":"","meta":[],"product_cat":[233,120,107,212,27],"product_tag":[],"_links":{"self":[{"href":"http:\/\/www.believecasuals.com\/ar\/wp-json\/wp\/v2\/product\/35602"}],"collection":[{"href":"http:\/\/www.believecasuals.com\/ar\/wp-json\/wp\/v2\/product"}],"about":[{"href":"http:\/\/www.believecasuals.com\/ar\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.believecasuals.com\/ar\/wp-json\/wp\/v2\/media\/35606"}],"wp:attachment":[{"href":"http:\/\/www.believecasuals.com\/ar\/wp-json\/wp\/v2\/media?parent=35602"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"http:\/\/www.believecasuals.com\/ar\/wp-json\/wp\/v2\/product_cat?post=35602"},{"taxonomy":"product_tag","embeddable":true,"href":"http:\/\/www.believecasuals.com\/ar\/wp-json\/wp\/v2\/product_tag?post=35602"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}